{"id":3077,"date":"2024-07-02T20:19:37","date_gmt":"2024-07-02T20:19:37","guid":{"rendered":"https:\/\/demo.productiveminds.com\/productive-commerce\/?page_id=3077"},"modified":"2024-07-29T01:48:55","modified_gmt":"2024-07-29T01:48:55","slug":"comparison-expanded","status":"publish","type":"page","link":"https:\/\/demo.productiveminds.com\/productive-commerce\/comparison-expanded\/","title":{"rendered":"Comparison &#8211; Expanded"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3077\" class=\"elementor elementor-3077\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b34de75 e-con-full e-flex e-con e-parent\" data-id=\"b34de75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8b6e748 e-con-full siteMaxWidth e-flex e-con e-child\" data-id=\"8b6e748\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d13db elementor-widget elementor-widget-productive_elementor_widget_compare_list\" data-id=\"e3d13db\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;section_content_layout_enable_accordion_toggle&quot;:&quot;toggle_disabled&quot;,&quot;section_content_settings_unique_id&quot;:&quot;section_unique_id_956056718_62294396&quot;,&quot;section_style_each_item_col_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;section_style_each_item_col_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;section_style_each_item_col_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"productive_elementor_widget_compare_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"site-body-container_box_full productive-paddable-section page_main_section_container align_page_none section_with_themed_bg siteMaxWidth_Std section_spacing_none shapeable-image-default\">\n                <div class=\"site-body-container_box_full       \">\n            <div class=\"site-body-container_box\">\n                <div class=\"site-body-container_box_uno\">\n            <script>\n        function productive_commerce_js_generate_compare_cookie_from_ls() {\n            let compare_slug = '';\n            let site = 'httpsdemoproductivemindscomproductivecommerce';\n            pcpCompares    = localStorage.getItem( 'pcpCompares'+site );\n            if( null !== pcpCompares && '' !== pcpCompares ) {\n                pcpComparesData = JSON.parse( pcpCompares );\n                compare_slug = pcpComparesData[0].slug;\n            }            \n            let name = 'pcp_compare';\n            let expires = parseInt( '1788418607' );\n            let path = '\/';\n            let domain = '';\n            let secure = '1';\n            let cookie_param = name + \"=\" + compare_slug + \"; expires=\" + expires + \"; path=\" + path + \"; domain=\" + domain + \"; secure=\" + secure ;\n            document.cookie = cookie_param;\n        }\n        productive_commerce_js_generate_compare_cookie_from_ls();\n    <\/script>\n<div class=\"woocommerce-notices-wrapper\"><\/div>    <div class=\"productiveminds_section woocommerce compare grided elementor \" id=\"section_unique_id_956056718_62294396\">\n        <div class=\"productiveminds_section_uno\">\n                <div class=\"productiveminds_section_no_content_found compare \">Nothing to compare. Please select two or more products to compare, then revisit this page.<\/div>\n     \n        <\/div><!-- productiveminds_section_uno -->\n    <\/div><!-- productiveminds_section -->\n                    <\/div>\n            <\/div>\n        <\/div>\n                <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Compare Nothing to compare. Please select two or more products to compare, then revisit this page.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"one-column-full-width.php","meta":{"footnotes":""},"class_list":["post-3077","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/pages\/3077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/comments?post=3077"}],"version-history":[{"count":7,"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/pages\/3077\/revisions"}],"predecessor-version":[{"id":3323,"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/pages\/3077\/revisions\/3323"}],"wp:attachment":[{"href":"https:\/\/demo.productiveminds.com\/productive-commerce\/wp-json\/wp\/v2\/media?parent=3077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}